{"id":5065,"date":"2025-11-17T11:51:22","date_gmt":"2025-11-17T10:51:22","guid":{"rendered":"https:\/\/danishfibres.com\/fib-2\/"},"modified":"2026-02-03T15:02:16","modified_gmt":"2026-02-03T14:02:16","slug":"wiking-fibrillierte-faser","status":"publish","type":"page","link":"https:\/\/danishfibres.com\/de\/konstruktionsfasern\/wiking-fibrillierte-faser\/","title":{"rendered":"Wiking fibrillierte faser"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"5065\" class=\"elementor elementor-5065 elementor-3639\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bfb6bea e-flex e-con-boxed e-con e-parent\" data-id=\"bfb6bea\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-da5c8b6 elementor-widget elementor-widget-breadcrumbs\" data-id=\"da5c8b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/danishfibres.com\/de\/home\/\">Danish Fibres<\/a><\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1689802 e-con-full e-flex e-con e-child\" data-id=\"1689802\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bc2a16a elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"bc2a16a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"213\" src=\"https:\/\/danishfibres.com\/wp-content\/uploads\/fibrillated_construction_fibres_danish_fibres-1024x272.jpg\" class=\"attachment-large size-large wp-image-1390\" alt=\"Fibrillated Fibres for concrete reinforcement\" srcset=\"https:\/\/danishfibres.com\/wp-content\/uploads\/fibrillated_construction_fibres_danish_fibres-1024x272.jpg 1024w, https:\/\/danishfibres.com\/wp-content\/uploads\/fibrillated_construction_fibres_danish_fibres-300x80.jpg 300w, https:\/\/danishfibres.com\/wp-content\/uploads\/fibrillated_construction_fibres_danish_fibres-768x204.jpg 768w, https:\/\/danishfibres.com\/wp-content\/uploads\/fibrillated_construction_fibres_danish_fibres.jpg 1129w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fdd29be e-con-full e-flex e-con e-child\" data-id=\"fdd29be\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-bf841bf e-con-full e-flex e-con e-child\" data-id=\"bf841bf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ffc82bf h1 elementor-widget elementor-widget-heading\" data-id=\"ffc82bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Wiking\u00ae Fibrillierte Betonfasern \u2013 Risskontrolle, Festigkeit &amp; Dauerhaftigkeit<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d753032 elementor-widget__width-initial df-text elementor-widget elementor-widget-text-editor\" data-id=\"d753032\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Wiking\u00ae Fibrillierte Fasern sind multifilamente Polypropylenfasern, geeignet f\u00fcr alle Arten von Betonprodukten \u2013 insbesondere M\u00f6rtel, Spritzbeton und Betonfertigteile. Die Fasern verhindern die Rissbildung und sorgen f\u00fcr eine hohe Zugfestigkeit. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8795527 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8795527\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-aadb830 e-grid e-con-full e-con e-child\" data-id=\"aadb830\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-e9d4d32 e-con-full e-flex e-con e-child\" data-id=\"e9d4d32\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0476709 elementor-widget elementor-widget-heading\" data-id=\"0476709\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Fibrillierte Standard-Serie<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8cc49a2 e-con-full e-flex e-con e-child\" data-id=\"8cc49a2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cc63c5b elementor-widget elementor-widget-heading\" data-id=\"cc63c5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Wiking\u00ae Standard Fine<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b5bd58 elementor-widget elementor-widget-heading\" data-id=\"3b5bd58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">2\u201336 mm, 361 MPa<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-626413b e-con-full e-flex e-con e-child\" data-id=\"626413b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8c9a5da elementor-widget elementor-widget-heading\" data-id=\"8c9a5da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Wiking\u00ae Standard Extra<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d656367 elementor-widget elementor-widget-heading\" data-id=\"d656367\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">12\u201336 mm, 361 MPa<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cc9df86 e-con-full e-flex e-con e-child\" data-id=\"cc9df86\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-45d3851 elementor-widget elementor-widget-heading\" data-id=\"45d3851\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Wiking\u00ae Standard Coarse<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d637f4b elementor-widget elementor-widget-heading\" data-id=\"d637f4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">12\u201336 mm, 786 MPa<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0b37bdf e-con-full e-flex e-con e-child\" data-id=\"0b37bdf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8a7eacf elementor-widget elementor-widget-heading\" data-id=\"8a7eacf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Fibrillierte Spezial-Serie<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-65de6e6 e-con-full e-flex e-con e-child\" data-id=\"65de6e6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e7768da elementor-widget elementor-widget-heading\" data-id=\"e7768da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Wiking\u00ae 3000 m<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7e1824 elementor-widget elementor-widget-heading\" data-id=\"a7e1824\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">12\u201336 mm, 299 MPa<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b16b7e1 e-con-full e-flex e-con e-child\" data-id=\"b16b7e1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-091078c elementor-widget elementor-widget-heading\" data-id=\"091078c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Wiking<span style=\"font-size: 14.25px;line-height: 0;position: relative;vertical-align: baseline;top: -0.5em\">\u00ae<\/span> 8000 m SP<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6951ada elementor-widget elementor-widget-heading\" data-id=\"6951ada\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><span style=\"font-size: 17.2px\">48 mm, 618 MPa<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-78e9ac1 e-con-full e-flex e-con e-child\" data-id=\"78e9ac1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f893ff7 elementor-widget elementor-widget-heading\" data-id=\"f893ff7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Wiking\u00ae WEFF+ P<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f4dadf elementor-widget elementor-widget-heading\" data-id=\"7f4dadf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">2-4 mm, 655 MPa<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18e9a4d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"18e9a4d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-120981a elementor-align-center elementor-widget elementor-widget-button\" data-id=\"120981a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/danishfibres.com\/de\/kontakt\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Kontaktieren Sie unser Vertriebsteam<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62319fb elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"62319fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-48b7b73 e-con-full e-flex e-con e-child\" data-id=\"48b7b73\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f2099b5 elementor-widget elementor-widget-heading\" data-id=\"f2099b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hauptvorteile der gesamten Produktreihe<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-da209d2 e-grid e-con-full e-con e-child\" data-id=\"da209d2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-c3794ef e-con-full e-flex e-con e-child\" data-id=\"c3794ef\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-f28ce36 e-con-full e-flex e-con e-child\" data-id=\"f28ce36\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e68815a elementor-widget elementor-widget-image\" data-id=\"e68815a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/danishfibres.com\/wp-content\/uploads\/piktogram_Cracks-Prevention.png\" class=\"attachment-large size-large wp-image-4403\" alt=\"Crack Prevention\" srcset=\"https:\/\/danishfibres.com\/wp-content\/uploads\/piktogram_Cracks-Prevention.png 500w, https:\/\/danishfibres.com\/wp-content\/uploads\/piktogram_Cracks-Prevention-300x300.png 300w, https:\/\/danishfibres.com\/wp-content\/uploads\/piktogram_Cracks-Prevention-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c03865 elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"3c03865\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Verhindert plastische <br>Schwind- und <br>Setzungsrisse<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d8d459e e-con-full e-flex e-con e-child\" data-id=\"d8d459e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-b9814cf e-con-full e-flex e-con e-child\" data-id=\"b9814cf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-15352ae elementor-widget elementor-widget-image\" data-id=\"15352ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/danishfibres.com\/wp-content\/uploads\/piktogram_Ductility.png\" class=\"attachment-large size-large wp-image-5059\" alt=\"\" srcset=\"https:\/\/danishfibres.com\/wp-content\/uploads\/piktogram_Ductility.png 500w, https:\/\/danishfibres.com\/wp-content\/uploads\/piktogram_Ductility-300x300.png 300w, https:\/\/danishfibres.com\/wp-content\/uploads\/piktogram_Ductility-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-457279d elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"457279d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Erh\u00f6ht Zug-, <br>Biege- und <br>Schlagfestigkeit<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8f026c7 e-con-full e-flex e-con e-child\" data-id=\"8f026c7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-702ebc6 e-con-full e-flex e-con e-child\" data-id=\"702ebc6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6df6f92 elementor-widget elementor-widget-image\" data-id=\"6df6f92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/danishfibres.com\/wp-content\/uploads\/piktogram_Flexural-Strength.png\" class=\"attachment-large size-large wp-image-5060\" alt=\"\" srcset=\"https:\/\/danishfibres.com\/wp-content\/uploads\/piktogram_Flexural-Strength.png 500w, https:\/\/danishfibres.com\/wp-content\/uploads\/piktogram_Flexural-Strength-300x300.png 300w, https:\/\/danishfibres.com\/wp-content\/uploads\/piktogram_Flexural-Strength-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6bd37ce elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"6bd37ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Verbessert <br>Duktilit\u00e4t und <br>Fugenabst\u00e4nde<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-93bd72e e-con-full e-flex e-con e-child\" data-id=\"93bd72e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-0547661 e-con-full e-flex e-con e-child\" data-id=\"0547661\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-833eb42 elementor-widget elementor-widget-image\" data-id=\"833eb42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/danishfibres.com\/wp-content\/uploads\/piktogram_Impact-Resistance.png\" class=\"attachment-large size-large wp-image-5061\" alt=\"\" srcset=\"https:\/\/danishfibres.com\/wp-content\/uploads\/piktogram_Impact-Resistance.png 500w, https:\/\/danishfibres.com\/wp-content\/uploads\/piktogram_Impact-Resistance-300x300.png 300w, https:\/\/danishfibres.com\/wp-content\/uploads\/piktogram_Impact-Resistance-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df6b92b elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"df6b92b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Reduziert <br>Feuchtigkeitsaufnahme <br>und Schrumfung<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c5b7169 e-con-full e-flex e-con e-child\" data-id=\"c5b7169\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-88e756f e-con-full e-flex e-con e-child\" data-id=\"88e756f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aab749c elementor-widget elementor-widget-image\" data-id=\"aab749c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/danishfibres.com\/wp-content\/uploads\/piktogram_Resistance-Explosive.png\" class=\"attachment-large size-large wp-image-5062\" alt=\"\" srcset=\"https:\/\/danishfibres.com\/wp-content\/uploads\/piktogram_Resistance-Explosive.png 500w, https:\/\/danishfibres.com\/wp-content\/uploads\/piktogram_Resistance-Explosive-300x300.png 300w, https:\/\/danishfibres.com\/wp-content\/uploads\/piktogram_Resistance-Explosive-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45338ec elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"45338ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Nicht magnetisch<br>und chemikalienbest\u00e4ndig<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7e661c8 e-con-full e-flex e-con e-child\" data-id=\"7e661c8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-d79258b e-con-full e-flex e-con e-child\" data-id=\"d79258b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e9015e8 elementor-widget elementor-widget-image\" data-id=\"e9015e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/danishfibres.com\/wp-content\/uploads\/piktogram_Low-Air-Content.png\" class=\"attachment-large size-large wp-image-5063\" alt=\"\" srcset=\"https:\/\/danishfibres.com\/wp-content\/uploads\/piktogram_Low-Air-Content.png 500w, https:\/\/danishfibres.com\/wp-content\/uploads\/piktogram_Low-Air-Content-300x300.png 300w, https:\/\/danishfibres.com\/wp-content\/uploads\/piktogram_Low-Air-Content-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c878bbe elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"c878bbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Geringer Luftgehalt <br>(1\u20133 %) aufgrund von <br>Oberfl\u00e4chenbehandlung<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-04e5e08 e-con-full e-flex e-con e-child\" data-id=\"04e5e08\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-b8cee51 e-con-full e-flex e-con e-child\" data-id=\"b8cee51\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b78b06a elementor-widget elementor-widget-image\" data-id=\"b78b06a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/danishfibres.com\/wp-content\/uploads\/piktogram_Flame-Retardant.png\" class=\"attachment-large size-large wp-image-5064\" alt=\"\" srcset=\"https:\/\/danishfibres.com\/wp-content\/uploads\/piktogram_Flame-Retardant.png 500w, https:\/\/danishfibres.com\/wp-content\/uploads\/piktogram_Flame-Retardant-300x300.png 300w, https:\/\/danishfibres.com\/wp-content\/uploads\/piktogram_Flame-Retardant-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-16db723 elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"16db723\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Flammhemmende <br>Eigenschaften<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8cd742 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a8cd742\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e3f9dcb e-con-full e-flex e-con e-child\" data-id=\"e3f9dcb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-88fc695 elementor-widget elementor-widget-heading\" data-id=\"88fc695\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Produktvergleichstabelle<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6eecc01 elementor-widget elementor-widget-wp-widget-custom_html\" data-id=\"6eecc01\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wp-widget-custom_html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"textwidget custom-html-widget\"><section class=\"product-grid\">\r\n  <article class=\"product\">\r\n    <h3 class=\"product-title\">Standard Fine<\/h3>\r\n\r\n    <dl>\r\n      <div>\r\n        <dt>L\u00e4nge (mm)<\/dt>\r\n<dd>2\u201336<\/dd>\r\n      <\/div>\r\n\r\n      <div>\r\n        <dt>Zugfestigkeit (MPa)<\/dt>\r\n<dd>361<\/dd>\r\n      <\/div>\r\n\r\n      <div>\r\n        <dt>Flammhemmend<\/dt>\r\n<dd>Yes \u25cf\u25cf\u25cf\u25cf\u25cf<\/dd>\r\n      <\/div>\r\n\r\n      <div>\r\n        <dt>Anwendung<\/dt>\r\n<dd>\r\nK\u00fcstenschutz, Trockenm\u00f6rtel, Betonfertigteile, Bodenplatten, Innenb\u00f6den, Gehwege und Stra\u00dfen, Fundamente f\u00fcr Windkraftanlagen und \u00c4hnliches\r\n<\/dd> \r\n      <\/div>\r\n\r\n     <div><dt>Data sheet<\/dt><dd class=\"product-download\"><img decoding=\"async\" src=\"https:\/\/danishfibres.com\/wp-content\/uploads\/Sheet.png\"><a href=\"https:\/\/danishfibres.com\/wp-content\/uploads\/Wiking_Standard_Fine_DE.pdf\" target=\"_blank\">Download<\/a><\/dd><\/div>\r\n    <\/dl>\r\n  <\/article>\r\n\r\n\r\n  <article class=\"product\">\r\n    <h3 class=\"product-title\">Standard Extra<\/h3>\r\n    <dl>\r\n      <div><dt>L\u00e4nge (mm)<\/dt><dd>12\u201336<\/dd><\/div>\r\n      <div><dt>Zugfestigkeit (MPa)<\/dt><dd>361<\/dd><\/div>\r\n      <div><dt>Flammhemmend<\/dt><dd>Yes \u25cf\u25cf\u25cf\u25cf\u25cf<\/dd><\/div>\r\n      <div><dt>Anwendung<\/dt><dd>Innenb\u00f6den, Landwirtschaftliche Geb\u00e4ude, Betonprodukte, Produktionsbereiche, Parkdecks, Estrich<\/dd><\/div>\r\n      <div><dt>Data sheet<\/dt><dd class=\"product-download\"><img decoding=\"async\" src=\"https:\/\/danishfibres.com\/wp-content\/uploads\/Sheet.png\"><a href=\"https:\/\/danishfibres.com\/wp-content\/uploads\/Wiking_Standard_Extra_DE.pdf\" target=\"_blank\">Download<\/a><\/dd><\/div>\r\n    <\/dl>\r\n  <\/article>\r\n\r\n  <article class=\"product\">\r\n    <h3 class=\"product-title\">Standard Coarse<\/h3>\r\n    <dl>\r\n      <div><dt>L\u00e4nge (mm)<\/dt><dd>12\u201336<\/dd><\/div>\r\n      <div><dt>Zugfestigkeit (MPa)<\/dt><dd>786<\/dd><\/div>\r\n      <div><dt>Flammhemmend<\/dt><dd>Yes \u25cf\u25cf\u25cf\u25cf\u25cf<\/dd><\/div>\r\n      <div><dt>Anwendung<\/dt><dd>Hallenb\u00f6den, Landwirtschaftliche Geb\u00e4ude, Betonprodukte, Produktionsbereiche, Parkdecks, Estrich<\/dd><\/div>\r\n      <div><dt>Data sheet<\/dt><dd class=\"product-download\"><img decoding=\"async\" src=\"https:\/\/danishfibres.com\/wp-content\/uploads\/Sheet.png\"><a href=\"https:\/\/danishfibres.com\/wp-content\/uploads\/Wiking_Standard_Coarse_DE.pdf\" target=\"_blank\">Download<\/a><\/dd><\/div>\r\n    <\/dl>\r\n  <\/article>\r\n\r\n  <article class=\"product\">\r\n    <h2 class=\"product-title\">3000 m<\/h2>\r\n    <dl>\r\n      <div><dt>L\u00e4nge (mm)<\/dt><dd>12\u201336<\/dd><\/div>\r\n      <div><dt>Zugfestigkeit (MPa)<\/dt><dd>299<\/dd><\/div>\r\n      <div><dt>Flammhemmend<\/dt><dd>Yes \u25cf\u25cf\u25cf\u25cb\u25cb<\/dd><\/div>\r\n      <div><dt>Anwendung<\/dt><dd>Hallenb\u00f6den, Landwirtschaftliche Geb\u00e4ude, Betonprodukte, Produktionsbereiche, Parkdecks, Estrich<\/dd><\/div>\r\n     <div><dt>Data sheet<\/dt><dd class=\"product-download\"><img decoding=\"async\" src=\"https:\/\/danishfibres.com\/wp-content\/uploads\/Sheet.png\"><a href=\"https:\/\/danishfibres.com\/wp-content\/uploads\/Wiking_3000m_DE.pdf\" target=\"_blank\">Download<\/a><\/dd><\/div>\r\n    <\/dl>\r\n  <\/article>\r\n  \r\n  <article class=\"product\">\r\n    <h3 class=\"product-title\">8000 m SP<\/h3>\r\n    <dl>\r\n      <div><dt>L\u00e4nge (mm)<\/dt><dd>48<\/dd><\/div>\r\n      <div><dt>Zugfestigkeit (MPa)<\/dt><dd>618<\/dd><\/div>\r\n      <div><dt>Flammhemmend<\/dt><dd>Yes \u25cf\u25cf\u25cf\u25cb\u25cb<\/dd><\/div>\r\n      <div><dt>Anwendung<\/dt><dd>Hallenb\u00f6den, Landwirtschaftliche Geb\u00e4ude, Betonprodukte, Produktionsbereiche, Parkdecks, Estrich<\/dd><\/div>\r\n      <div><dt>Data sheet<\/dt><dd class=\"product-download\"><img decoding=\"async\" src=\"https:\/\/danishfibres.com\/wp-content\/uploads\/Sheet.png\"><a href=\"https:\/\/danishfibres.com\/wp-content\/uploads\/Wiking_8000m_SP_DE.pdf\" target=\"_blank\">Download<\/a><\/dd><\/div>\r\n    <\/dl>\r\n  <\/article>\r\n\r\n  <article class=\"product\">\r\n    <h3 class=\"product-title\">WEFF+ P<\/h3>\r\n    <dl>\r\n      <div><dt>L\u00e4nge (mm)<\/dt><dd>2\u20134<\/dd><\/div>\r\n      <div><dt>Zugfestigkeit (MPa)<\/dt><dd>655<\/dd><\/div>\r\n      <div><dt>Flammhemmend<\/dt><dd>Yes \u25cf\u25cf\u25cf\u25cf\u25cf<\/dd><\/div>\r\n      <div><dt>Anwendung<\/dt><dd>Trockenm\u00f6rtel, Innenb\u00f6den, Betonfertigteile, Dachplatten, Fassadenplatten\r\n<\/dd><\/div>\r\n      <div><dt>Data sheet<\/dt><dd class=\"product-download\"><img decoding=\"async\" src=\"https:\/\/danishfibres.com\/wp-content\/uploads\/Sheet.png\"><a href=\"https:\/\/danishfibres.com\/wp-content\/uploads\/Wiking_WEFFP_DE.pdf\" target=\"_blank\">Download<\/a><\/dd><\/div>\r\n    <\/dl>\r\n    \r\n  <\/article>\r\n\r\n<\/section><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9ea2698 e-con-full e-flex e-con e-child\" data-id=\"9ea2698\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-265489b elementor-widget elementor-widget-heading\" data-id=\"265489b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Typische Anwendungen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-530bfe3 elementor-widget elementor-widget-text-editor\" data-id=\"530bfe3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li>Betonfertigteile (z. B. Betonplatten, Fundamente f\u00fcr Windkraftanlagen, K\u00fcstenschutz)<\/li><li>Innenb\u00f6den und Terrassen im Au\u00dfenbereich<\/li><li>Landwirtschaftliche und Industriegeb\u00e4ude<\/li><li>Spritzbeton, M\u00f6rtel, Trockenmischungen und Putz<\/li><li>Parkh\u00e4user, Tunnel, Produktionsbereiche<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c77fab elementor-widget__width-initial elementor-widget elementor-widget-n-accordion\" data-id=\"6c77fab\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:300,&quot;sizes&quot;:[]},&quot;max_items_expended&quot;:&quot;one&quot;}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1130\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1130\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Produktbeschreibung <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1130\" class=\"elementor-element elementor-element-092526c e-con-full e-flex e-con e-child\" data-id=\"092526c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0c63272 elementor-widget elementor-widget-text-editor\" data-id=\"0c63272\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Wiking\u00ae Fibrillierte Fasern bestehen aus reinem Polypropylen, das zu sehr feinen und schlanken Fibrillen extrudiert wurde. Die unregelm\u00e4\u00dfige, kantige Struktur der Fibrillen sorgt f\u00fcr eine hervorragende mechanische Haftung im Beton. <\/p><p><strong>Verhinderung von Rissbildung<\/strong><br>Beim Zumischen von Wiking\u00ae Fibrillierten Fasern entsteht eine dreidimensionale Matrix, die plastische Schwind- und Setzungsrisse verhindert. Dies gew\u00e4hrleistet eine st\u00e4rkere und dauerhaftere Betonstruktur. <\/p><p><strong>Geringes Gewicht &#8211; hohe Haftf\u00e4higkeit<\/strong><br>Polypropylenfasern haben eine sehr geringe Dichte von 0,91 g\/cm\u00b3. Die Spezialserie ist mit einem anorganischen Material modifiziert, um die Dichte auf 1,01 g\/cm\u00b3 zu erh\u00f6hen \u2013 ideal f\u00fcr eine verbesserte Haftung im Beton.  <\/p><p><strong>Brandschutz und Best\u00e4ndigkeit gegen explosive Splitterwirkung<\/strong><br>Wiking\u00ae Fasern sind auch als Brandschutzmaterial im Tunnelbau geeignet. Im Brandfall schmelzen die Fasern und bilden kleine Kapillarporen, die die explosive Splitterwirkung verz\u00f6gert und zus\u00e4tzliche Zeit f\u00fcr die Rettung von im Tunnelbrand eingeschlossenen Personen verl\u00e4ngert. <\/p><p><strong>Best\u00e4ndigkeit gegen S\u00e4uren und Basen<\/strong><br>Polypropylenfasern sind best\u00e4ndig gegen S\u00e4uren und Basen und verhindern so die Beeintr\u00e4chtigung von Aussehen und Haltbarkeit des Betons auch unter anspruchsvollen Bedingungen <\/p><p><strong>Luftgehalt unter 1 %<\/strong><br>Die Oberfl\u00e4che der Wiking\u00ae Mikrofasern ist speziell behandelt, um die Dispergier- und Haftf\u00e4higkeit zu erh\u00f6hen und den Luftgehalt im faserverst\u00e4rkten Beton unter 1 % zu halten. <\/p><p><strong>Flexible Produktion nach Bedarf<\/strong><br>Wir produzieren fibrillierte Fasern in \u00fcber 50 Varianten. Feinere Typen sind besonders f\u00fcr Trockenmischungen geeignet, w\u00e4hrend gr\u00f6bere Typen f\u00fcr maximale Haftung und Festigkeit im Beton sorgen. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1131\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1131\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Produktbeschreibung Wiking\u00ae WEFF+ P <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1131\" class=\"elementor-element elementor-element-75cf384 e-flex e-con-boxed e-con e-child\" data-id=\"75cf384\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c0f4cc5 elementor-widget elementor-widget-text-editor\" data-id=\"c0f4cc5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Wiking\u00ae WEFF+ P ist eine hoch fibrillierte Multifilamentfaser aus Polypropylen (PP)<br><\/strong>Die verzweigte Struktur gew\u00e4hrleistet eine hervorragende Dispergierf\u00e4higkeit, eine gro\u00dfe Oberfl\u00e4che und eine optimale Haftung in zementgebundenen Baustoffen und unterst\u00fctzt gleichzeitig Nassverfahren sowie zellstoffbasierte Anwendungen.<\/p><p><strong>Verhinderung von Fr\u00fchschwindrissen<br><\/strong>Die hohe Dispergierf\u00e4higkeit und die verzweigte Struktur bilden ein dichtes Fasernetz, das Fr\u00fchschwindrisse verhindert und eine gleichm\u00e4\u00dfige Lastverteilung und Langzeitbest\u00e4ndigkeit sicherstellt. <\/p><p><strong>Optimiert f\u00fcr Zement und Faserzement<br><\/strong>Verbessert Festigkeit, Struktur und Verarbeitungseigenschaften in Produkten wie Trockenm\u00f6rtel, Fertigteilen, Dachplatten und Fassadenplatten.<\/p><p><strong>Sekund\u00e4re Anwendungen<br><\/strong>Auch geeignet f\u00fcr hei\u00dfsiegelf\u00e4higes Papier, Filtermedien, Beschichtungen und Klebstoffe und ist somit eine vielseitige L\u00f6sung f\u00fcr Nassverfahren und zellstoffbasierte Produkte.<\/p><p><strong>Gro\u00dfe Oberfl\u00e4che f\u00fcr maximale Haftung<br><\/strong>Sorgt f\u00fcr eine exzellente Faser-zu-Faser-Bindung und verbesserte Bindungsf\u00e4higkeit in zementgebundenen Materialien und gew\u00e4hrleistet so eine maximale Zugfestigkeits\u00fcbertragung.<\/p><p><strong>Best\u00e4ndigkeit und Haltbarkeit<br><\/strong>Wiking\u00ae WEFF+ P wird aus Polypropylen mit Zusatzstoffen hergestellt, ist best\u00e4ndig gegen S\u00e4uren und Basen und beh\u00e4lt sein Aussehen und seine Leistungsf\u00e4higkeit auch unter extremen Bedingungen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f994155 e-con-full e-flex e-con e-child\" data-id=\"f994155\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3118410 elementor-widget elementor-widget-heading\" data-id=\"3118410\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FAQ \u2013 H\u00e4ufig gestellte Fragen <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1325720 elementor-widget__width-initial elementor-widget elementor-widget-n-accordion\" data-id=\"1325720\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;max_items_expended&quot;:&quot;multiple&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:200,&quot;sizes&quot;:[]},&quot;default_state&quot;:&quot;expanded&quot;}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2000\" class=\"e-n-accordion-item\" open>\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"true\" aria-controls=\"e-n-accordion-item-2000\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Sind alle Wiking\u00ae-Fasern flammhemmend? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2000\" class=\"elementor-element elementor-element-9e588fd e-con-full e-flex e-con e-child\" data-id=\"9e588fd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bc1d266 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"bc1d266\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Ja, die Flammhemmung ist jedoch von der Faserstruktur abh\u00e4ngig. F\u00fcr weitere Informationen kontaktieren Sie uns bitte. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2001\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2001\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Was ist der Unterschied zwischen fibrillierten und Standardfasern? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2001\" class=\"elementor-element elementor-element-7a581bb e-flex e-con-boxed e-con e-child\" data-id=\"7a581bb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b57f451 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"b57f451\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tFibrillierte Fasern bestehen aus kleinen Fibrillen, wodurch eine gro\u00dfe Oberfl\u00e4che und gute Haftung gew\u00e4hrleistet werden. Standardfasern sind entweder Monofilamente (einzelne Str\u00e4nge) oder Faserb\u00fcndel, die Festigkeit und Flexibilit\u00e4t bieten.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2002\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2002\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Welche Faser eignet sich f\u00fcr Trockenm\u00f6rtel oder Tunnelbau? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2002\" class=\"elementor-element elementor-element-6258a71 e-flex e-con-boxed e-con e-child\" data-id=\"6258a71\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6216c4e elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"6216c4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Wiking\u00ae Standard Fine eignen sich aufgrund seiner feinen Struktur und seiner schwer entflammbaren Eigenschaften f\u00fcr Trockenm\u00f6rtel- und Tunnelbauanwendungen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2003\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2003\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> K\u00f6nnen Wiking\u00ae Fasern Stahlmatten ersetzen? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2003\" class=\"elementor-element elementor-element-2082160 e-flex e-con-boxed e-con e-child\" data-id=\"2082160\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1e8708d elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"1e8708d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Ja \u2013 mehrere Varianten sind als Alternative zur Risskontrolle konzipiert und bieten eine verbesserte Dispergierung und erh\u00f6hte Haltbarkeit.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2004\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2004\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Sind Wiking\u00ae Fasern mit allen Betontypen kompatibel? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2004\" class=\"elementor-element elementor-element-ab5d78e e-flex e-con-boxed e-con e-child\" data-id=\"ab5d78e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-181bd45 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"181bd45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Ja \u2013 sie eignen sich f\u00fcr M\u00f6rtel, Spritzbeton, Trockenbeton und tragende Konstruktionen und sind in \u00fcber 50 Varianten f\u00fcr ma\u00dfgeschneiderte L\u00f6sungen f\u00fcr Ihr Projekt erh\u00e4ltlich.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-410c3ba e-con-full e-flex e-con e-child\" data-id=\"410c3ba\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-9125c94 e-grid e-con-full e-con e-child\" data-id=\"9125c94\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-db98da1 e-con-full e-flex e-con e-child\" data-id=\"db98da1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9421d3b elementor-widget elementor-widget-heading\" data-id=\"9421d3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vereinbaren Sie einen Termin mit unserem Vertriebsteam<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8312a59 e-con-full e-flex e-con e-child\" data-id=\"8312a59\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-02ce602 e-con-full e-flex e-con e-child\" data-id=\"02ce602\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-98f0883 sales-title elementor-widget elementor-widget-heading\" data-id=\"98f0883\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">CEO\/President<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc9a6cc sales-name elementor-widget elementor-widget-heading\" data-id=\"fc9a6cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Palle Kuntz<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-385de2b elementor-widget elementor-widget-heading\" data-id=\"385de2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><a href=\"tel:+4524659615\">+45 24 65 96 15<\/a><\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ba82bd elementor-widget elementor-widget-button\" data-id=\"2ba82bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"mailto:pku@danishfibres.dk\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">pku@danishfibres.dk<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f7a493c e-con-full e-flex e-con e-child\" data-id=\"f7a493c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-059a1bb sales-title elementor-widget elementor-widget-heading\" data-id=\"059a1bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Vertriebsleiter<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-298075b sales-name elementor-widget elementor-widget-heading\" data-id=\"298075b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">David Etzerodt<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1657f3 elementor-widget elementor-widget-heading\" data-id=\"b1657f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><a href=\"tel:+4520580599\">+45 20 58 05 99<\/a><\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-985f5e0 elementor-widget elementor-widget-button\" data-id=\"985f5e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"mailto:dke@danishfibres.dk\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">dke@danishfibres.dk<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ec74218 e-con-full e-flex e-con e-child\" data-id=\"ec74218\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-78da241 elementor-widget elementor-widget-image\" data-id=\"78da241\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"527\" height=\"278\" src=\"https:\/\/danishfibres.com\/wp-content\/uploads\/Our_Sales_Team_Danish_Fibres_subpage.jpg\" class=\"attachment-large size-large wp-image-244\" alt=\"\" srcset=\"https:\/\/danishfibres.com\/wp-content\/uploads\/Our_Sales_Team_Danish_Fibres_subpage.jpg 527w, https:\/\/danishfibres.com\/wp-content\/uploads\/Our_Sales_Team_Danish_Fibres_subpage-300x158.jpg 300w\" sizes=\"(max-width: 527px) 100vw, 527px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a71e542 e-flex e-con-boxed e-con e-parent\" data-id=\"a71e542\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6fbc379 e-con-full e-flex e-con e-child\" data-id=\"6fbc379\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-28fc328 e-con-full e-flex e-con e-child\" data-id=\"28fc328\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3476cc7 elementor-widget elementor-widget-heading\" data-id=\"3476cc7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Datenbl\u00e4tter<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da6bcbc elementor-widget elementor-widget-heading\" data-id=\"da6bcbc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Laden Sie die Datenbl\u00e4tter im PDF-Format herunter, um mehr \u00fcber die einzelnen Wiking\u00ae Fibrillierte Fasern zu erfahren.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c820539 elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-widget elementor-widget-loop-grid\" data-id=\"c820539\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;template_id&quot;:3718,&quot;_skin&quot;:&quot;post&quot;,&quot;columns&quot;:&quot;3&quot;,&quot;columns_tablet&quot;:&quot;2&quot;,&quot;columns_mobile&quot;:&quot;1&quot;,&quot;edit_handle_selector&quot;:&quot;[data-elementor-type=\\&quot;loop-item\\&quot;]&quot;,&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"loop-grid.post\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-loop-container elementor-grid\" role=\"list\">\n\t\t<style id=\"loop-3718\">.elementor-3718 .elementor-element.elementor-element-2ab950a{--display:flex;--flex-direction:column;--container-widget-width:100%;--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;--gap:1rem 1rem;--row-gap:1rem;--column-gap:1rem;--padding-top:0px;--padding-bottom:0px;--padding-left:0px;--padding-right:0px;}.elementor-widget-theme-post-title .elementor-heading-title{font-family:var( --e-global-typography-primary-font-family ), Sans-serif;font-size:var( --e-global-typography-primary-font-size );font-weight:var( --e-global-typography-primary-font-weight );line-height:var( --e-global-typography-primary-line-height );color:var( --e-global-color-primary );}.elementor-3718 .elementor-element.elementor-element-b2353f5{--display:flex;--flex-direction:row;--container-widget-width:calc( ( 1 - var( --container-widget-flex-grow ) ) * 100% );--container-widget-height:100%;--container-widget-flex-grow:1;--container-widget-align-self:stretch;--flex-wrap-mobile:wrap;--align-items:center;--gap:10px 10px;--row-gap:10px;--column-gap:10px;--padding-top:0px;--padding-bottom:0px;--padding-left:0px;--padding-right:0px;}.elementor-widget-image .widget-image-caption{color:var( --e-global-color-text );font-family:var( --e-global-typography-text-font-family ), Sans-serif;font-size:var( --e-global-typography-text-font-size );font-weight:var( --e-global-typography-text-font-weight );line-height:var( --e-global-typography-text-line-height );}.elementor-3718 .elementor-element.elementor-element-5418879{width:var( --container-widget-width, 1.75rem );max-width:1.75rem;--container-widget-width:1.75rem;--container-widget-flex-grow:0;}.elementor-widget-button .elementor-button{font-family:var( --e-global-typography-accent-font-family ), Sans-serif;font-weight:var( --e-global-typography-accent-font-weight );background-color:var( --e-global-color-accent );}.elementor-3718 .elementor-element.elementor-element-5657382 .elementor-button-content-wrapper{flex-direction:row;}.elementor-3718 .elementor-element.elementor-element-5657382 .elementor-button{fill:var( --e-global-color-accent );color:var( --e-global-color-accent );background-color:var( --e-global-color-dfb8c9a );border-radius:100px 100px 100px 100px;}.elementor-3718 .elementor-element.elementor-element-5657382 .elementor-button:hover, .elementor-3718 .elementor-element.elementor-element-5657382 .elementor-button:focus{color:var( --e-global-color-1de00cd );background-color:var( --e-global-color-accent );}.elementor-3718 .elementor-element.elementor-element-5657382 .elementor-button:hover svg, .elementor-3718 .elementor-element.elementor-element-5657382 .elementor-button:focus svg{fill:var( --e-global-color-1de00cd );}.elementor-3718 .elementor-element.elementor-element-5657382.elementor-element{--flex-grow:1;--flex-shrink:0;}@media(min-width:768px){.elementor-3718 .elementor-element.elementor-element-b2353f5{--width:100%;}}@media(max-width:1024px){.elementor-widget-theme-post-title .elementor-heading-title{font-size:var( --e-global-typography-primary-font-size );line-height:var( --e-global-typography-primary-line-height );}.elementor-widget-image .widget-image-caption{font-size:var( --e-global-typography-text-font-size );line-height:var( --e-global-typography-text-line-height );}}@media(max-width:767px){.elementor-widget-theme-post-title .elementor-heading-title{font-size:var( --e-global-typography-primary-font-size );line-height:var( --e-global-typography-primary-line-height );}.elementor-widget-image .widget-image-caption{font-size:var( --e-global-typography-text-font-size );line-height:var( --e-global-typography-text-line-height );}}<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"3718\" class=\"elementor elementor-3718 e-loop-item e-loop-item-2189 post-2189 data-sheet type-data-sheet status-publish hentry\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-2ab950a e-flex e-con-boxed e-con e-parent\" data-id=\"2ab950a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d4e062 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"8d4e062\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Wiking\u00ae 3000 m<\/h1>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b2353f5 e-con-full e-flex e-con e-child\" data-id=\"b2353f5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5418879 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"5418879\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/danishfibres.com\/wp-content\/uploads\/Wiking_3000m_DE.pdf\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"78\" height=\"108\" src=\"https:\/\/danishfibres.com\/wp-content\/uploads\/Sheet.png\" class=\"attachment-large size-large wp-image-3751\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5657382 elementor-widget elementor-widget-button\" data-id=\"5657382\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/danishfibres.com\/wp-content\/uploads\/Wiking_3000m_DE.pdf\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-download\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M216 0h80c13.3 0 24 10.7 24 24v168h87.7c17.8 0 26.7 21.5 14.1 34.1L269.7 378.3c-7.5 7.5-19.8 7.5-27.3 0L90.1 226.1c-12.6-12.6-3.7-34.1 14.1-34.1H192V24c0-13.3 10.7-24 24-24zm296 376v112c0 13.3-10.7 24-24 24H24c-13.3 0-24-10.7-24-24V376c0-13.3 10.7-24 24-24h146.7l49 49c20.1 20.1 52.5 20.1 72.6 0l49-49H488c13.3 0 24 10.7 24 24zm-124 88c0-11-9-20-20-20s-20 9-20 20 9 20 20 20 20-9 20-20zm64 0c0-11-9-20-20-20s-20 9-20 20 9 20 20 20 20-9 20-20z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Download<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"3718\" class=\"elementor elementor-3718 e-loop-item e-loop-item-2201 post-2201 data-sheet type-data-sheet status-publish hentry\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-2ab950a e-flex e-con-boxed e-con e-parent\" data-id=\"2ab950a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d4e062 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"8d4e062\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Wiking\u00ae 8000 SP<\/h1>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b2353f5 e-con-full e-flex e-con e-child\" data-id=\"b2353f5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5418879 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"5418879\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/danishfibres.com\/wp-content\/uploads\/Wiking_8000m_SP_DE.pdf\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"78\" height=\"108\" src=\"https:\/\/danishfibres.com\/wp-content\/uploads\/Sheet.png\" class=\"attachment-large size-large wp-image-3751\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5657382 elementor-widget elementor-widget-button\" data-id=\"5657382\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/danishfibres.com\/wp-content\/uploads\/Wiking_8000m_SP_DE.pdf\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-download\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M216 0h80c13.3 0 24 10.7 24 24v168h87.7c17.8 0 26.7 21.5 14.1 34.1L269.7 378.3c-7.5 7.5-19.8 7.5-27.3 0L90.1 226.1c-12.6-12.6-3.7-34.1 14.1-34.1H192V24c0-13.3 10.7-24 24-24zm296 376v112c0 13.3-10.7 24-24 24H24c-13.3 0-24-10.7-24-24V376c0-13.3 10.7-24 24-24h146.7l49 49c20.1 20.1 52.5 20.1 72.6 0l49-49H488c13.3 0 24 10.7 24 24zm-124 88c0-11-9-20-20-20s-20 9-20 20 9 20 20 20 20-9 20-20zm64 0c0-11-9-20-20-20s-20 9-20 20 9 20 20 20 20-9 20-20z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Download<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"3718\" class=\"elementor elementor-3718 e-loop-item e-loop-item-2204 post-2204 data-sheet type-data-sheet status-publish hentry\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-2ab950a e-flex e-con-boxed e-con e-parent\" data-id=\"2ab950a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d4e062 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"8d4e062\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Wiking\u00ae Standard Grob<\/h1>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b2353f5 e-con-full e-flex e-con e-child\" data-id=\"b2353f5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5418879 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"5418879\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/danishfibres.com\/wp-content\/uploads\/Wiking_Standard_Coarse_DE.pdf\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"78\" height=\"108\" src=\"https:\/\/danishfibres.com\/wp-content\/uploads\/Sheet.png\" class=\"attachment-large size-large wp-image-3751\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5657382 elementor-widget elementor-widget-button\" data-id=\"5657382\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/danishfibres.com\/wp-content\/uploads\/Wiking_Standard_Coarse_DE.pdf\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-download\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M216 0h80c13.3 0 24 10.7 24 24v168h87.7c17.8 0 26.7 21.5 14.1 34.1L269.7 378.3c-7.5 7.5-19.8 7.5-27.3 0L90.1 226.1c-12.6-12.6-3.7-34.1 14.1-34.1H192V24c0-13.3 10.7-24 24-24zm296 376v112c0 13.3-10.7 24-24 24H24c-13.3 0-24-10.7-24-24V376c0-13.3 10.7-24 24-24h146.7l49 49c20.1 20.1 52.5 20.1 72.6 0l49-49H488c13.3 0 24 10.7 24 24zm-124 88c0-11-9-20-20-20s-20 9-20 20 9 20 20 20 20-9 20-20zm64 0c0-11-9-20-20-20s-20 9-20 20 9 20 20 20 20-9 20-20z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Download<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"3718\" class=\"elementor elementor-3718 e-loop-item e-loop-item-2207 post-2207 data-sheet type-data-sheet status-publish hentry\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-2ab950a e-flex e-con-boxed e-con e-parent\" data-id=\"2ab950a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d4e062 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"8d4e062\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Wiking\u00ae Standard Extra<\/h1>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b2353f5 e-con-full e-flex e-con e-child\" data-id=\"b2353f5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5418879 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"5418879\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/danishfibres.com\/wp-content\/uploads\/Wiking_Standard_Extra_DE.pdf\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"78\" height=\"108\" src=\"https:\/\/danishfibres.com\/wp-content\/uploads\/Sheet.png\" class=\"attachment-large size-large wp-image-3751\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5657382 elementor-widget elementor-widget-button\" data-id=\"5657382\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/danishfibres.com\/wp-content\/uploads\/Wiking_Standard_Extra_DE.pdf\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-download\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M216 0h80c13.3 0 24 10.7 24 24v168h87.7c17.8 0 26.7 21.5 14.1 34.1L269.7 378.3c-7.5 7.5-19.8 7.5-27.3 0L90.1 226.1c-12.6-12.6-3.7-34.1 14.1-34.1H192V24c0-13.3 10.7-24 24-24zm296 376v112c0 13.3-10.7 24-24 24H24c-13.3 0-24-10.7-24-24V376c0-13.3 10.7-24 24-24h146.7l49 49c20.1 20.1 52.5 20.1 72.6 0l49-49H488c13.3 0 24 10.7 24 24zm-124 88c0-11-9-20-20-20s-20 9-20 20 9 20 20 20 20-9 20-20zm64 0c0-11-9-20-20-20s-20 9-20 20 9 20 20 20 20-9 20-20z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Download<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"3718\" class=\"elementor elementor-3718 e-loop-item e-loop-item-2210 post-2210 data-sheet type-data-sheet status-publish hentry\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-2ab950a e-flex e-con-boxed e-con e-parent\" data-id=\"2ab950a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d4e062 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"8d4e062\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Wiking\u00ae Standard Fine<\/h1>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b2353f5 e-con-full e-flex e-con e-child\" data-id=\"b2353f5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5418879 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"5418879\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/danishfibres.com\/wp-content\/uploads\/Wiking_Standard_Fine_DE.pdf\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"78\" height=\"108\" src=\"https:\/\/danishfibres.com\/wp-content\/uploads\/Sheet.png\" class=\"attachment-large size-large wp-image-3751\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5657382 elementor-widget elementor-widget-button\" data-id=\"5657382\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/danishfibres.com\/wp-content\/uploads\/Wiking_Standard_Fine_DE.pdf\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-download\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M216 0h80c13.3 0 24 10.7 24 24v168h87.7c17.8 0 26.7 21.5 14.1 34.1L269.7 378.3c-7.5 7.5-19.8 7.5-27.3 0L90.1 226.1c-12.6-12.6-3.7-34.1 14.1-34.1H192V24c0-13.3 10.7-24 24-24zm296 376v112c0 13.3-10.7 24-24 24H24c-13.3 0-24-10.7-24-24V376c0-13.3 10.7-24 24-24h146.7l49 49c20.1 20.1 52.5 20.1 72.6 0l49-49H488c13.3 0 24 10.7 24 24zm-124 88c0-11-9-20-20-20s-20 9-20 20 9 20 20 20 20-9 20-20zm64 0c0-11-9-20-20-20s-20 9-20 20 9 20 20 20 20-9 20-20z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Download<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"3718\" class=\"elementor elementor-3718 e-loop-item e-loop-item-5027 post-5027 data-sheet type-data-sheet status-publish hentry\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-2ab950a e-flex e-con-boxed e-con e-parent\" data-id=\"2ab950a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d4e062 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"8d4e062\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Wiking\u00ae WEFF+ P<\/h1>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b2353f5 e-con-full e-flex e-con e-child\" data-id=\"b2353f5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5418879 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"5418879\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/danishfibres.com\/wp-content\/uploads\/Wiking_WEFFP_DE.pdf\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"78\" height=\"108\" src=\"https:\/\/danishfibres.com\/wp-content\/uploads\/Sheet.png\" class=\"attachment-large size-large wp-image-3751\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5657382 elementor-widget elementor-widget-button\" data-id=\"5657382\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/danishfibres.com\/wp-content\/uploads\/Wiking_WEFFP_DE.pdf\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-download\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M216 0h80c13.3 0 24 10.7 24 24v168h87.7c17.8 0 26.7 21.5 14.1 34.1L269.7 378.3c-7.5 7.5-19.8 7.5-27.3 0L90.1 226.1c-12.6-12.6-3.7-34.1 14.1-34.1H192V24c0-13.3 10.7-24 24-24zm296 376v112c0 13.3-10.7 24-24 24H24c-13.3 0-24-10.7-24-24V376c0-13.3 10.7-24 24-24h146.7l49 49c20.1 20.1 52.5 20.1 72.6 0l49-49H488c13.3 0 24 10.7 24 24zm-124 88c0-11-9-20-20-20s-20 9-20 20 9 20 20 20 20-9 20-20zm64 0c0-11-9-20-20-20s-20 9-20 20 9 20 20 20 20-9 20-20z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Download<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-743d6e6 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"743d6e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/danishfibres.com\/de\/ueber-uns\/datenblaetter\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Alle Datenbl\u00e4tter anzeigen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-178d36b e-con-full e-flex e-con e-child\" data-id=\"178d36b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aff3652 elementor-widget elementor-widget-heading\" data-id=\"aff3652\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Weiterlesen<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7421e2a elementor-grid-4 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-widget elementor-widget-loop-grid\" data-id=\"7421e2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;template_id&quot;:3785,&quot;columns&quot;:4,&quot;_skin&quot;:&quot;post&quot;,&quot;columns_tablet&quot;:&quot;2&quot;,&quot;columns_mobile&quot;:&quot;1&quot;,&quot;edit_handle_selector&quot;:&quot;[data-elementor-type=\\&quot;loop-item\\&quot;]&quot;,&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"loop-grid.post\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-loop-container elementor-grid\" role=\"list\">\n\t\t<style id=\"loop-3785\">.elementor-3785 .elementor-element.elementor-element-3f30a52{--display:flex;--flex-direction:column;--container-widget-width:100%;--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;--padding-top:0px;--padding-bottom:0px;--padding-left:0px;--padding-right:0px;}.elementor-widget-theme-post-featured-image .widget-image-caption{color:var( --e-global-color-text );font-family:var( --e-global-typography-text-font-family ), Sans-serif;font-size:var( --e-global-typography-text-font-size );font-weight:var( --e-global-typography-text-font-weight );line-height:var( --e-global-typography-text-line-height );}.elementor-widget-heading .elementor-heading-title{font-family:var( --e-global-typography-primary-font-family ), Sans-serif;font-size:var( --e-global-typography-primary-font-size );font-weight:var( --e-global-typography-primary-font-weight );line-height:var( --e-global-typography-primary-line-height );color:var( --e-global-color-primary );}.elementor-3785 .elementor-element.elementor-element-7cba774 .elementor-heading-title{font-family:var( --e-global-typography-7ed151c-font-family ), Sans-serif;font-size:var( --e-global-typography-7ed151c-font-size );font-weight:var( --e-global-typography-7ed151c-font-weight );line-height:var( --e-global-typography-7ed151c-line-height );letter-spacing:var( --e-global-typography-7ed151c-letter-spacing );word-spacing:var( --e-global-typography-7ed151c-word-spacing );}.elementor-3785 .elementor-element.elementor-element-7cba774{padding:0px 0px 0px 0px;}@media(max-width:1024px){.elementor-widget-theme-post-featured-image .widget-image-caption{font-size:var( --e-global-typography-text-font-size );line-height:var( --e-global-typography-text-line-height );}.elementor-widget-heading .elementor-heading-title{font-size:var( --e-global-typography-primary-font-size );line-height:var( --e-global-typography-primary-line-height );}.elementor-3785 .elementor-element.elementor-element-7cba774 .elementor-heading-title{font-size:var( --e-global-typography-7ed151c-font-size );line-height:var( --e-global-typography-7ed151c-line-height );letter-spacing:var( --e-global-typography-7ed151c-letter-spacing );word-spacing:var( --e-global-typography-7ed151c-word-spacing );}}@media(max-width:767px){.elementor-widget-theme-post-featured-image .widget-image-caption{font-size:var( --e-global-typography-text-font-size );line-height:var( --e-global-typography-text-line-height );}.elementor-widget-heading .elementor-heading-title{font-size:var( --e-global-typography-primary-font-size );line-height:var( --e-global-typography-primary-line-height );}.elementor-3785 .elementor-element.elementor-element-7cba774 .elementor-heading-title{font-size:var( --e-global-typography-7ed151c-font-size );line-height:var( --e-global-typography-7ed151c-line-height );letter-spacing:var( --e-global-typography-7ed151c-letter-spacing );word-spacing:var( --e-global-typography-7ed151c-word-spacing );}}\/* Start custom CSS for theme-post-featured-image, class: .elementor-element-e13329b *\/.elementor-3785 .elementor-element.elementor-element-e13329b {\nheight: 100%;\n    overflow: hidden;\n    width: 100%;\n}\n.elementor-3785 .elementor-element.elementor-element-e13329b img {\n        width: 100%;\n    object-fit: cover;\n    aspect-ratio: 16 \/ 9;\n}\/* End custom CSS *\/\n\/* Start custom CSS for heading, class: .elementor-element-7cba774 *\/.elementor-3785 .elementor-element.elementor-element-7cba774 a{\n    font-weight: 700 !important;\n}\/* End custom CSS *\/<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"3785\" class=\"elementor elementor-3785 e-loop-item e-loop-item-4412 post-4412 feature-card type-feature-card status-publish has-post-thumbnail hentry visibility-asphaltfaser visibility-home\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-3f30a52 clickable-parent e-flex e-con-boxed e-con e-parent\" data-id=\"3f30a52\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e13329b elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"e13329b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"337\" src=\"https:\/\/danishfibres.com\/wp-content\/uploads\/AS-PE-Asphalt-Fibres-Danish-Fibres-2.jpg\" class=\"attachment-large size-large wp-image-4569\" alt=\"AS-PE - Asphaltfasern - Danish Fibres\" srcset=\"https:\/\/danishfibres.com\/wp-content\/uploads\/AS-PE-Asphalt-Fibres-Danish-Fibres-2.jpg 831w, https:\/\/danishfibres.com\/wp-content\/uploads\/AS-PE-Asphalt-Fibres-Danish-Fibres-2-300x126.jpg 300w, https:\/\/danishfibres.com\/wp-content\/uploads\/AS-PE-Asphalt-Fibres-Danish-Fibres-2-768x323.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7cba774 elementor-widget elementor-widget-heading\" data-id=\"7cba774\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/de\/so-bauen-wir-strassen-die-halten-und-sparen-dabei-millionen\/\">Stra\u00dfen bauen und Millionen sparen<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"3785\" class=\"elementor elementor-3785 e-loop-item e-loop-item-2599 post-2599 feature-card type-feature-card status-publish has-post-thumbnail hentry visibility-home\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-3f30a52 clickable-parent e-flex e-con-boxed e-con e-parent\" data-id=\"3f30a52\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e13329b elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"e13329b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"337\" src=\"https:\/\/danishfibres.com\/wp-content\/uploads\/Tunnels-Danish-Fibres.jpg\" class=\"attachment-large size-large wp-image-852\" alt=\"\" srcset=\"https:\/\/danishfibres.com\/wp-content\/uploads\/Tunnels-Danish-Fibres.jpg 830w, https:\/\/danishfibres.com\/wp-content\/uploads\/Tunnels-Danish-Fibres-300x127.jpg 300w, https:\/\/danishfibres.com\/wp-content\/uploads\/Tunnels-Danish-Fibres-768x324.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7cba774 elementor-widget elementor-widget-heading\" data-id=\"7cba774\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/de\/konstruktionsfasern\/anwendungen\/fasern-fuer-tunnel-und-brandschutz\/\">Tunnel<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"3785\" class=\"elementor elementor-3785 e-loop-item e-loop-item-2311 post-2311 feature-card type-feature-card status-publish has-post-thumbnail hentry visibility-basaltfasern visibility-gebundelt-fasern visibility-home visibility-makrofasern visibility-mikrofasern\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-3f30a52 clickable-parent e-flex e-con-boxed e-con e-parent\" data-id=\"3f30a52\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e13329b elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"e13329b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"269\" height=\"178\" src=\"https:\/\/danishfibres.com\/wp-content\/uploads\/turning_torso_construction_fibres_danish_fibres_thumb_L_2.jpg\" class=\"attachment-large size-large wp-image-1126\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7cba774 elementor-widget elementor-widget-heading\" data-id=\"7cba774\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/de\/fallstudien\/turning-torso\/\">Turning Torso<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"3785\" class=\"elementor elementor-3785 e-loop-item e-loop-item-2604 post-2604 feature-card type-feature-card status-publish has-post-thumbnail hentry visibility-asphaltfaser visibility-gebundelt-fasern visibility-home\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-3f30a52 clickable-parent e-flex e-con-boxed e-con e-parent\" data-id=\"3f30a52\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e13329b elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"e13329b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"255\" height=\"155\" src=\"https:\/\/danishfibres.com\/wp-content\/uploads\/basalt_super-b-fibres_danish_fibres_thumb.jpg\" class=\"attachment-large size-large wp-image-885\" alt=\"Basalt Super-B Fibres\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7cba774 elementor-widget elementor-widget-heading\" data-id=\"7cba774\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/de\/konstruktionsfasern\/wiking-basaltfasern\/\">Basaltfasern<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Wiking\u00ae Fibrillierte Betonfasern \u2013 Risskontrolle, Festigkeit &amp; Dauerhaftigkeit Wiking\u00ae Fibrillierte Fasern sind multifilamente Polypropylenfasern, geeignet f\u00fcr alle Arten von Betonprodukten \u2013 insbesondere M\u00f6rtel, Spritzbeton und Betonfertigteile. Die Fasern verhindern die Rissbildung und sorgen f\u00fcr eine hohe Zugfestigkeit. Fibrillierte Standard-Serie Wiking\u00ae Standard Fine 2\u201336 mm, 361 MPa Wiking\u00ae Standard Extra 12\u201336 mm, 361 MPa Wiking\u00ae Standard [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":2008,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-5065","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wiking fibrillierte faser - Danish Fibres<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/danishfibres.com\/de\/konstruktionsfasern\/wiking-fibrillierte-faser\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wiking fibrillierte faser - Danish Fibres\" \/>\n<meta property=\"og:description\" content=\"Wiking\u00ae Fibrillierte Betonfasern \u2013 Risskontrolle, Festigkeit &amp; Dauerhaftigkeit Wiking\u00ae Fibrillierte Fasern sind multifilamente Polypropylenfasern, geeignet f\u00fcr alle Arten von Betonprodukten \u2013 insbesondere M\u00f6rtel, Spritzbeton und Betonfertigteile. Die Fasern verhindern die Rissbildung und sorgen f\u00fcr eine hohe Zugfestigkeit. Fibrillierte Standard-Serie Wiking\u00ae Standard Fine 2\u201336 mm, 361 MPa Wiking\u00ae Standard Extra 12\u201336 mm, 361 MPa Wiking\u00ae Standard [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/danishfibres.com\/de\/konstruktionsfasern\/wiking-fibrillierte-faser\/\" \/>\n<meta property=\"og:site_name\" content=\"Danish Fibres\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-03T14:02:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/danishfibres.com\/wp-content\/uploads\/fibrillated_construction_fibres_danish_fibres.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1129\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/danishfibres.com\\\/de\\\/konstruktionsfasern\\\/wiking-fibrillierte-faser\\\/\",\"url\":\"https:\\\/\\\/danishfibres.com\\\/de\\\/konstruktionsfasern\\\/wiking-fibrillierte-faser\\\/\",\"name\":\"Wiking fibrillierte faser - Danish Fibres\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/danishfibres.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/danishfibres.com\\\/de\\\/konstruktionsfasern\\\/wiking-fibrillierte-faser\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/danishfibres.com\\\/de\\\/konstruktionsfasern\\\/wiking-fibrillierte-faser\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/danishfibres.com\\\/wp-content\\\/uploads\\\/fibrillated_construction_fibres_danish_fibres-1024x272.jpg\",\"datePublished\":\"2025-11-17T10:51:22+00:00\",\"dateModified\":\"2026-02-03T14:02:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/danishfibres.com\\\/de\\\/konstruktionsfasern\\\/wiking-fibrillierte-faser\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/danishfibres.com\\\/de\\\/konstruktionsfasern\\\/wiking-fibrillierte-faser\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/danishfibres.com\\\/de\\\/konstruktionsfasern\\\/wiking-fibrillierte-faser\\\/#primaryimage\",\"url\":\"https:\\\/\\\/danishfibres.com\\\/wp-content\\\/uploads\\\/fibrillated_construction_fibres_danish_fibres-1024x272.jpg\",\"contentUrl\":\"https:\\\/\\\/danishfibres.com\\\/wp-content\\\/uploads\\\/fibrillated_construction_fibres_danish_fibres-1024x272.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/danishfibres.com\\\/de\\\/konstruktionsfasern\\\/wiking-fibrillierte-faser\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Danish Fibres\",\"item\":\"https:\\\/\\\/danishfibres.com\\\/de\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Konstruktionsfasern\",\"item\":\"https:\\\/\\\/danishfibres.com\\\/de\\\/konstruktionsfasern\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Wiking fibrillierte faser\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/danishfibres.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/danishfibres.com\\\/de\\\/\",\"name\":\"Danish Fibres\",\"description\":\"Benefit from 40 years experience\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/danishfibres.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wiking fibrillierte faser - Danish Fibres","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/danishfibres.com\/de\/konstruktionsfasern\/wiking-fibrillierte-faser\/","og_locale":"de_DE","og_type":"article","og_title":"Wiking fibrillierte faser - Danish Fibres","og_description":"Wiking\u00ae Fibrillierte Betonfasern \u2013 Risskontrolle, Festigkeit &amp; Dauerhaftigkeit Wiking\u00ae Fibrillierte Fasern sind multifilamente Polypropylenfasern, geeignet f\u00fcr alle Arten von Betonprodukten \u2013 insbesondere M\u00f6rtel, Spritzbeton und Betonfertigteile. Die Fasern verhindern die Rissbildung und sorgen f\u00fcr eine hohe Zugfestigkeit. Fibrillierte Standard-Serie Wiking\u00ae Standard Fine 2\u201336 mm, 361 MPa Wiking\u00ae Standard Extra 12\u201336 mm, 361 MPa Wiking\u00ae Standard [&hellip;]","og_url":"https:\/\/danishfibres.com\/de\/konstruktionsfasern\/wiking-fibrillierte-faser\/","og_site_name":"Danish Fibres","article_modified_time":"2026-02-03T14:02:16+00:00","og_image":[{"width":1129,"height":300,"url":"https:\/\/danishfibres.com\/wp-content\/uploads\/fibrillated_construction_fibres_danish_fibres.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/danishfibres.com\/de\/konstruktionsfasern\/wiking-fibrillierte-faser\/","url":"https:\/\/danishfibres.com\/de\/konstruktionsfasern\/wiking-fibrillierte-faser\/","name":"Wiking fibrillierte faser - Danish Fibres","isPartOf":{"@id":"https:\/\/danishfibres.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/danishfibres.com\/de\/konstruktionsfasern\/wiking-fibrillierte-faser\/#primaryimage"},"image":{"@id":"https:\/\/danishfibres.com\/de\/konstruktionsfasern\/wiking-fibrillierte-faser\/#primaryimage"},"thumbnailUrl":"https:\/\/danishfibres.com\/wp-content\/uploads\/fibrillated_construction_fibres_danish_fibres-1024x272.jpg","datePublished":"2025-11-17T10:51:22+00:00","dateModified":"2026-02-03T14:02:16+00:00","breadcrumb":{"@id":"https:\/\/danishfibres.com\/de\/konstruktionsfasern\/wiking-fibrillierte-faser\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/danishfibres.com\/de\/konstruktionsfasern\/wiking-fibrillierte-faser\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/danishfibres.com\/de\/konstruktionsfasern\/wiking-fibrillierte-faser\/#primaryimage","url":"https:\/\/danishfibres.com\/wp-content\/uploads\/fibrillated_construction_fibres_danish_fibres-1024x272.jpg","contentUrl":"https:\/\/danishfibres.com\/wp-content\/uploads\/fibrillated_construction_fibres_danish_fibres-1024x272.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/danishfibres.com\/de\/konstruktionsfasern\/wiking-fibrillierte-faser\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Danish Fibres","item":"https:\/\/danishfibres.com\/de\/home\/"},{"@type":"ListItem","position":2,"name":"Konstruktionsfasern","item":"https:\/\/danishfibres.com\/de\/konstruktionsfasern\/"},{"@type":"ListItem","position":3,"name":"Wiking fibrillierte faser"}]},{"@type":"WebSite","@id":"https:\/\/danishfibres.com\/de\/#website","url":"https:\/\/danishfibres.com\/de\/","name":"Danish Fibres","description":"Benefit from 40 years experience","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/danishfibres.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/danishfibres.com\/de\/wp-json\/wp\/v2\/pages\/5065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/danishfibres.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/danishfibres.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/danishfibres.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/danishfibres.com\/de\/wp-json\/wp\/v2\/comments?post=5065"}],"version-history":[{"count":12,"href":"https:\/\/danishfibres.com\/de\/wp-json\/wp\/v2\/pages\/5065\/revisions"}],"predecessor-version":[{"id":5211,"href":"https:\/\/danishfibres.com\/de\/wp-json\/wp\/v2\/pages\/5065\/revisions\/5211"}],"up":[{"embeddable":true,"href":"https:\/\/danishfibres.com\/de\/wp-json\/wp\/v2\/pages\/2008"}],"wp:attachment":[{"href":"https:\/\/danishfibres.com\/de\/wp-json\/wp\/v2\/media?parent=5065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}